{"id":3,"date":"2024-04-04T09:15:42","date_gmt":"2024-04-04T06:15:42","guid":{"rendered":"https:\/\/sisu.ut.ee\/eckf\/home-0\/"},"modified":"2026-05-07T16:36:52","modified_gmt":"2026-05-07T13:36:52","slug":"home-0","status":"publish","type":"page","link":"https:\/\/sisu.ut.ee\/eckf\/","title":{"rendered":"ReConnect China"},"content":{"rendered":"<p><\/p>\n\n\n<div class=\"wp-block-site-logo\"><a href=\"https:\/\/sisu.ut.ee\/eckf\/\" class=\"custom-logo-link\" rel=\"home\"><img loading=\"lazy\" decoding=\"async\" width=\"377\" height=\"73\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo.png\" class=\"custom-logo\" alt=\"ECKF\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo.png 955w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo-300x58.png 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo-768x149.png 768w\" sizes=\"auto, (max-width: 377px) 100vw, 377px\"><\/a><\/div>\n\n\n<h3 class=\"wp-block-heading\">\u00a0<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">ReConnect China Dialog? Conditions, Constraints, and Futures of EU\u2013China Engagement<\/h3>\n\n\n\n<p><strong>12 June, 2026<br>Egmont Palace, Place du Petit Sablon, 8, B-1000, Brussels<\/strong><\/p>\n\n\n\n<p>The conference \u201cReConnect China Dialogue? Conditions, Constraints, and Futures of EU\u2013China Engagement\u201d offers a multidimensional overview of the current state of EU\u2013China relations, bringing together perspectives from economics, politics, technology, and international affairs.<\/p>\n\n\n\n<p>The programme is structured to explore possible futures of EU\u2013China engagement by examining key turning points, emerging constraints, and alternative scenarios shaping the relationship. Particular attention is given to recent internal developments in China \u2014 including technological, economic, and social transformations \u2014 as well as China\u2019s expanding global ambitions in the political and strategic arenas, and how these dynamics may influence its engagement with the European Union.<\/p>\n\n\n\n<p>In addition, conference panels explore new and evolving geographical dimensions of China\u2019s economic and political influence, with a focus on regions such as the Arctic and Africa, where interests increasingly intersect with those of the EU.<\/p>\n\n\n\n<p>The final session synthesises these discussions by outlining potential scenarios for future EU\u2013China engagement, highlighting risks, opportunities, and strategic choices facing European policymakers.<\/p>\n\n\n\n<p><strong>IN A SNAPSHOT<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Panel topics:<\/strong> EU-China de-risking approach, foreign policy, international relations, science and technology, trade and economy.<\/li>\n\n\n\n<li><strong>Structure of the program:<\/strong> 1 day, 3 plenary sessions and 3 parallel sessions, and plenary panels; each panel has 1 moderator and 3 panel discussants.<\/li>\n\n\n\n<li><strong>Key-note speakers, moderators, and participants:<\/strong> high-level scientists, policymakers, and economists; 150 participants;<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/forms.cloud.microsoft\/Pages\/ResponsePage.aspx?id=F2M1bQQNvEq2toyXc4hbsMyh21J3XOFLpv6tS2CxWK1UQk4yUkRPSDZUWkRGQUZBMjBGQzdJRE1FTS4u\">Conference registration<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-red-color\">Registration deadline 4th of June, 2026<\/mark><\/p>\n\n\n\n<p>More information: <br><strong>Anastasia Sinitsyna<\/strong>,\u00a0\u201cReConnect China\u201d Project Manager<br><a href=\"mailto:anastasia.sinitsyna@ut.ee\">anastasia.sinitsyna@ut.ee<\/a><\/p>\n\n\n\n<p>The conference has been arranged in the framework of the <a href=\"https:\/\/www.reconnect-china.ugent.be\/\">\u2018ReConnect China\u2019 project<\/a> led by the Ghent University<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<hr>\n<p><strong>PROJECT PARTNERS<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-176\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo_UGent_NL_RGB_2400_kleur_witbg-1-300x240.png\" alt=\"\" width=\"278\" height=\"222\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo_UGent_NL_RGB_2400_kleur_witbg-1-300x240.png 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo_UGent_NL_RGB_2400_kleur_witbg-1.png 510w\" sizes=\"auto, (max-width: 278px) 100vw, 278px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-84\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Aasia-keskus_eng_sinine-1-300x78.png\" alt=\"\" width=\"300\" height=\"78\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Aasia-keskus_eng_sinine-1-300x78.png 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Aasia-keskus_eng_sinine-1-1024x267.png 1024w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Aasia-keskus_eng_sinine-1-768x200.png 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Aasia-keskus_eng_sinine-1.png 1494w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-80\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo_intero-300x122.jpg\" alt=\"\" width=\"300\" height=\"122\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo_intero-300x122.jpg 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo_intero-1024x417.jpg 1024w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo_intero-768x313.jpg 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo_intero-1536x626.jpg 1536w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo_intero-2048x834.jpg 2048w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/logo_intero-1920x782.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-81\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/rugr_logoen_rood_rgb-300x83.png\" alt=\"\" width=\"300\" height=\"83\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/rugr_logoen_rood_rgb-300x83.png 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/rugr_logoen_rood_rgb-1024x282.png 1024w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/rugr_logoen_rood_rgb-768x211.png 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/rugr_logoen_rood_rgb-1536x423.png 1536w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/rugr_logoen_rood_rgb.png 1780w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-120\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/a756e402-342e-4604-a5c7-e64f0df09a89-300x190.gif\" alt=\"\" width=\"202\" height=\"128\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-95\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Uni_Logo_2016-300x150.jpeg\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Uni_Logo_2016-300x150.jpeg 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Uni_Logo_2016-1024x512.jpeg 1024w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Uni_Logo_2016-768x384.jpeg 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Uni_Logo_2016-1536x768.jpeg 1536w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Uni_Logo_2016-1920x960.jpeg 1920w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Uni_Logo_2016.jpeg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">\u00a0 \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-123\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-Elcano-2013-300x136.png\" alt=\"\" width=\"245\" height=\"111\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-Elcano-2013-300x136.png 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-Elcano-2013-1024x464.png 1024w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-Elcano-2013-768x348.png 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-Elcano-2013.png 1046w\" sizes=\"auto, (max-width: 245px) 100vw, 245px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-131\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/UTU_logo_EN_RGB-300x112.png\" alt=\"\" width=\"300\" height=\"112\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/UTU_logo_EN_RGB-300x112.png 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/UTU_logo_EN_RGB-768x286.png 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/UTU_logo_EN_RGB.png 828w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-133\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-IFRI-ENGLISH-300x276.jpg\" alt=\"\" width=\"185\" height=\"170\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-IFRI-ENGLISH-300x276.jpg 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-IFRI-ENGLISH-1024x942.jpg 1024w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-IFRI-ENGLISH-768x706.jpg 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-IFRI-ENGLISH-1536x1412.jpg 1536w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-IFRI-ENGLISH-2048x1883.jpg 2048w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Logo-IFRI-ENGLISH-1920x1765.jpg 1920w\" sizes=\"auto, (max-width: 185px) 100vw, 185px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-134\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/UP_logo_horizont_en-300x137.png\" alt=\"\" width=\"300\" height=\"137\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/UP_logo_horizont_en-300x137.png 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/UP_logo_horizont_en-768x350.png 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/UP_logo_horizont_en.png 855w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-182\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Macao.jpg\" alt=\"\" width=\"102\" height=\"103\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Macao.jpg 224w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Macao-150x150.jpg 150w\" sizes=\"auto, (max-width: 102px) 100vw, 102px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-135\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/ENG-white-full-logo-300x70.jpg\" alt=\"\" width=\"300\" height=\"70\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/ENG-white-full-logo-300x70.jpg 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/ENG-white-full-logo-1024x240.jpg 1024w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/ENG-white-full-logo-768x180.jpg 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/ENG-white-full-logo.jpg 1277w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-142\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/ZSI-Logo_Quer_comp-300x70.jpg\" alt=\"\" width=\"300\" height=\"70\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/ZSI-Logo_Quer_comp-300x70.jpg 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/ZSI-Logo_Quer_comp-1024x239.jpg 1024w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/ZSI-Logo_Quer_comp-768x179.jpg 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/ZSI-Logo_Quer_comp.jpg 1310w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-177\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/egmont-spf-300x196.png\" alt=\"\" width=\"200\" height=\"131\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/egmont-spf-300x196.png 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/egmont-spf.png 368w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-178\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Innovation-Norway-300x168.png\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Innovation-Norway-300x168.png 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Innovation-Norway-768x430.png 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/Innovation-Norway.png 898w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><\/p>\n<hr>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-197\" src=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/EU_funded_en-300x63.jpg\" alt=\"\" width=\"300\" height=\"63\" srcset=\"https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/EU_funded_en-300x63.jpg 300w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/EU_funded_en-1024x215.jpg 1024w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/EU_funded_en-768x161.jpg 768w, https:\/\/sisu.ut.ee\/wp-content\/uploads\/sites\/692\/EU_funded_en.jpg 1100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 ReConnect China Dialog? Conditions, Constraints, and Futures of EU\u2013China Engagement 12 June, 2026Egmont Palace, Place du Petit Sablon, 8, B-1000, Brussels The conference \u201cReConnect China Dialogue? Conditions, Constraints, and Futures of EU\u2013China Engagement\u201d offers a multidimensional overview of the &#8230;<\/p>\n","protected":false},"author":29,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sisu.ut.ee\/eckf\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sisu.ut.ee\/eckf\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sisu.ut.ee\/eckf\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sisu.ut.ee\/eckf\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/sisu.ut.ee\/eckf\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":30,"href":"https:\/\/sisu.ut.ee\/eckf\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":491,"href":"https:\/\/sisu.ut.ee\/eckf\/wp-json\/wp\/v2\/pages\/3\/revisions\/491"}],"wp:attachment":[{"href":"https:\/\/sisu.ut.ee\/eckf\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}